{"id":27,"count":1,"description":"","link":"https:\/\/skinarttraining.com\/ca\/course-category\/tattooing\/","name":"Tattooing","slug":"tattooing","taxonomy":"product_cat","parent":0,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/skinarttraining.com\/ca\/wp-json\/wp\/v2\/product_cat\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/skinarttraining.com\/ca\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/skinarttraining.com\/ca\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"wp:post_type":[{"href":"https:\/\/skinarttraining.com\/ca\/wp-json\/wp\/v2\/product?product_cat=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}